{"id":41,"date":"2019-05-01T17:47:15","date_gmt":"2019-05-01T15:47:15","guid":{"rendered":"https:\/\/staging.odysem.com\/?post_type=product&amp;p=41"},"modified":"2026-07-12T08:15:21","modified_gmt":"2026-07-12T06:15:21","slug":"gel-articulations-muscles","status":"publish","type":"product","link":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/","title":{"rendered":"Gel au silicium organique Si+ 65ml pour articulations et muscles"},"content":{"rendered":"<div class=\"tab-content\">\n<p>Ce gel au silicium organique vous permet de soulager vos douleurs localement. Gr\u00e2ce au silicium qu\u2019il contient, ainsi que ses extraits v\u00e9g\u00e9taux et ses autres ingr\u00e9dients, il apporte le soin n\u00e9cessaire directement l\u00e0 o\u00f9 il faut.<\/p>\n<p>En l\u2019appliquant sur la zone douloureuse, il p\u00e9n\u00e8tre imm\u00e9diatement dans votre peau. Jusque dans vos articulations et vos muscles. Ses effets anti-inflammatoires et anti-douleurs agissent donc au c\u0153ur du probl\u00e8me.<\/p>\n<p>Pour intensifier l\u2019action locale de ce gel, nous vous recommandons une cure de notre compl\u00e9ment alimentaire buvable au silicium organique.<\/p>\n<p>Comme tous les produits Si+, ce gel contient \u00e9galement des sels min\u00e9raux et de l\u2019huile de p\u00e9pins de pamplemousse. Ce qui nous permet de vous offrir un produit ultra concentr\u00e9 en silicium et garanti sans conservateur chimique dangereux.<\/p>\n<p>Pour encore plus d\u2019efficacit\u00e9, nous avons d\u00e9cid\u00e9 d\u2019y ajouter des extraits v\u00e9g\u00e9taux 100% bio. Leur s\u00e9lection a \u00e9t\u00e9 m\u00fbrement r\u00e9fl\u00e9chie par nos experts pour vous garantir les meilleurs effets anti-douleurs, anti-inflammatoires et anti-infectieux.<\/p>\n<p>Vous y retrouverez notamment des huiles essentielles de pin sylvestre, de menthe poivr\u00e9e, de thym a feuilles de Sariette et de Gaulth\u00e9rie odorante.<\/p>\n<p>Mais surtout, un mac\u00e9rat de Centella Asiatica qui est une plante reconnue pour ses propri\u00e9t\u00e9s cicatrisantes, anti-inflammatoires et anti-rhumatismales. Elle est d\u2019ailleurs utilis\u00e9e en m\u00e9decine ayurv\u00e9dique et m\u00e9decine traditionnelle chinoise.<\/p>\n<p>Le MSM qu\u2019il contient permet d\u2019apporter du souffre \u00e0 votre corps. Cet oligo-\u00e9l\u00e9ment participe \u00e0 la qualit\u00e9 de vos tissus conjonctifs, tout comme le silicium. Son action sur votre corps est avant tout anti-inflammatoire et anti-douleur. Le MSM est fortement utilis\u00e9 pour soulager l\u2019arthrose.<\/p>\n<p>Avec ce gel enrichi au silicium organique, vous pourrez enfin soulager vos douleurs et retrouver votre mobilit\u00e9.<\/p>\n<p class=\"read-more\"><a class=\"btn btn-read-more\" href=\"#\">Lire plus<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Combat la douleur et l\u2019inflammation dans les articulations, muscles et tendons<\/p>\n<ul>\n<li>R\u00e9pare et entretient les cartilages<\/li>\n<li>Anti-douleur<\/li>\n<li>Extraits v\u00e9g\u00e9taux 100% bio<\/li>\n<li>Sans conservateur chimique<\/li>\n<\/ul>\n","protected":false},"featured_media":88,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18],"product_tag":[],"class_list":{"0":"post-41","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-silicium-organique","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Si+ Silicium Organique Gel pour Articulations et Muscles 65ml<\/title>\n<meta name=\"description\" content=\"Soulagez vos douleurs articulaires et musculaires avec ce gel au silicium organique. Gr\u00e2ce ses extraits v\u00e9g\u00e9taux 100% bio, il vous soulage imm\u00e9diatement !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si+ Silicium Organique Gel pour Articulations et Muscles 65ml\" \/>\n<meta property=\"og:description\" content=\"Soulagez vos douleurs articulaires et musculaires avec ce gel au silicium organique. Gr\u00e2ce ses extraits v\u00e9g\u00e9taux 100% bio, il vous soulage imm\u00e9diatement !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/\" \/>\n<meta property=\"og:site_name\" content=\"Soles Mundi Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-12T06:15:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"816\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/\",\"url\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/\",\"name\":\"Si+ Silicium Organique Gel pour Articulations et Muscles 65ml\",\"isPartOf\":{\"@id\":\"https:\/\/soles-mundi.com\/es-es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png\",\"datePublished\":\"2019-05-01T15:47:15+00:00\",\"dateModified\":\"2026-07-12T06:15:21+00:00\",\"description\":\"Soulagez vos douleurs articulaires et musculaires avec ce gel au silicium organique. Gr\u00e2ce ses extraits v\u00e9g\u00e9taux 100% bio, il vous soulage imm\u00e9diatement !\",\"breadcrumb\":{\"@id\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#primaryimage\",\"url\":\"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png\",\"contentUrl\":\"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png\",\"width\":816,\"height\":730,\"caption\":\"\\\"Gel au silicium organique pour soigner les articulations et les muscles\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soles-mundi.com\/es-es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/soles-mundi.com\/es-es\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gel au silicium organique Si+ 65ml pour articulations et muscles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soles-mundi.com\/es-es\/#website\",\"url\":\"https:\/\/soles-mundi.com\/es-es\/\",\"name\":\"Soles Mundi Espa\u00f1a\",\"description\":\"Un site utilisant Les sites de Soles Mundi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soles-mundi.com\/es-es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si+ Silicium Organique Gel pour Articulations et Muscles 65ml","description":"Soulagez vos douleurs articulaires et musculaires avec ce gel au silicium organique. Gr\u00e2ce ses extraits v\u00e9g\u00e9taux 100% bio, il vous soulage imm\u00e9diatement !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/","og_locale":"es_ES","og_type":"article","og_title":"Si+ Silicium Organique Gel pour Articulations et Muscles 65ml","og_description":"Soulagez vos douleurs articulaires et musculaires avec ce gel au silicium organique. Gr\u00e2ce ses extraits v\u00e9g\u00e9taux 100% bio, il vous soulage imm\u00e9diatement !","og_url":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/","og_site_name":"Soles Mundi Espa\u00f1a","article_modified_time":"2026-07-12T06:15:21+00:00","og_image":[{"width":816,"height":730,"url":"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/","url":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/","name":"Si+ Silicium Organique Gel pour Articulations et Muscles 65ml","isPartOf":{"@id":"https:\/\/soles-mundi.com\/es-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#primaryimage"},"image":{"@id":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#primaryimage"},"thumbnailUrl":"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png","datePublished":"2019-05-01T15:47:15+00:00","dateModified":"2026-07-12T06:15:21+00:00","description":"Soulagez vos douleurs articulaires et musculaires avec ce gel au silicium organique. Gr\u00e2ce ses extraits v\u00e9g\u00e9taux 100% bio, il vous soulage imm\u00e9diatement !","breadcrumb":{"@id":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#primaryimage","url":"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png","contentUrl":"https:\/\/soles-mundi.com\/es-es\/wp-content\/uploads\/sites\/4\/2019\/05\/gel-silicium-organique-articulations-muscles-816x730-1.png","width":816,"height":730,"caption":"\"Gel au silicium organique pour soigner les articulations et les muscles\""},{"@type":"BreadcrumbList","@id":"https:\/\/soles-mundi.com\/es-es\/producto\/gel-articulations-muscles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soles-mundi.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/soles-mundi.com\/es-es\/shop\/"},{"@type":"ListItem","position":3,"name":"Gel au silicium organique Si+ 65ml pour articulations et muscles"}]},{"@type":"WebSite","@id":"https:\/\/soles-mundi.com\/es-es\/#website","url":"https:\/\/soles-mundi.com\/es-es\/","name":"Soles Mundi Espa\u00f1a","description":"Un site utilisant Les sites de Soles Mundi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soles-mundi.com\/es-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/product\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/comments?post=41"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/media\/88"}],"wp:attachment":[{"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/product_brand?post=41"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/product_cat?post=41"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soles-mundi.com\/es-es\/wp-json\/wp\/v2\/product_tag?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}